{"id":7693,"date":"2019-03-10T22:19:59","date_gmt":"2019-03-10T22:19:59","guid":{"rendered":"https:\/\/www.giantwithin.org\/?page_id=7693"},"modified":"2019-03-10T23:04:57","modified_gmt":"2019-03-10T23:04:57","slug":"toyins-blog","status":"publish","type":"page","link":"https:\/\/www.giantwithin.org\/index.php\/blog\/toyins-blog\/","title":{"rendered":"Toyin&#8217;s Blog"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<figure id=\"attachment_7598\" aria-describedby=\"caption-attachment-7598\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7598\" src=\"https:\/\/www.giantwithin.org\/wp-content\/uploads\/2019\/03\/Toyin-300x288.jpg\" alt=\"Toyin John\" width=\"300\" height=\"288\" srcset=\"https:\/\/www.giantwithin.org\/wp-content\/uploads\/2019\/03\/Toyin-300x288.jpg 300w, https:\/\/www.giantwithin.org\/wp-content\/uploads\/2019\/03\/Toyin-768x736.jpg 768w, https:\/\/www.giantwithin.org\/wp-content\/uploads\/2019\/03\/Toyin-600x575.jpg 600w, https:\/\/www.giantwithin.org\/wp-content\/uploads\/2019\/03\/Toyin.jpg 794w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-7598\" class=\"wp-caption-text\">Toyin John<\/figcaption><\/figure>\n<p>Welcome to my Blog page.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_basic_grid post_type=&#8221;post&#8221; max_items=&#8221;10&#8243; style=&#8221;load-more&#8221; show_filter=&#8221;yes&#8221; btn_color=&#8221;purple&#8221; btn_add_icon=&#8221;true&#8221; grid_id=&#8221;vc_gid:1552262844284-f1bfb130-4292-9&#8243; taxonomies=&#8221;51&#8243; filter_source=&#8221;category&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Welcome to my Blog page.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_basic_grid post_type=&#8221;post&#8221; max_items=&#8221;10&#8243; style=&#8221;load-more&#8221; show_filter=&#8221;yes&#8221; btn_color=&#8221;purple&#8221; btn_add_icon=&#8221;true&#8221; grid_id=&#8221;vc_gid:1552262844284-f1bfb130-4292-9&#8243; taxonomies=&#8221;51&#8243; filter_source=&#8221;category&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":6600,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7693","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Toyin&#039;s Blog - Giant Within Ministries<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.giantwithin.org\/index.php\/blog\/toyins-blog\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toyin&#039;s Blog - Giant Within Ministries\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] Welcome to my Blog page.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_basic_grid post_type=&#8221;post&#8221; max_items=&#8221;10&#8243; style=&#8221;load-more&#8221; show_filter=&#8221;yes&#8221; btn_color=&#8221;purple&#8221; btn_add_icon=&#8221;true&#8221; grid_id=&#8221;vc_gid:1552262844284-f1bfb130-4292-9&#8243; taxonomies=&#8221;51&#8243; filter_source=&#8221;category&#8221;][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.giantwithin.org\/index.php\/blog\/toyins-blog\/\" \/>\n<meta property=\"og:site_name\" content=\"Giant Within Ministries\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-10T23:04:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.giantwithin.org\/wp-content\/uploads\/2019\/03\/Toyin-300x288.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.giantwithin.org\\\/index.php\\\/blog\\\/toyins-blog\\\/\",\"url\":\"https:\\\/\\\/www.giantwithin.org\\\/index.php\\\/blog\\\/toyins-blog\\\/\",\"name\":\"Toyin's Blog - Giant Within Ministries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.giantwithin.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.giantwithin.org\\\/index.php\\\/blog\\\/toyins-blog\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.giantwithin.org\\\/index.php\\\/blog\\\/toyins-blog\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.giantwithin.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Toyin-300x288.jpg\",\"datePublished\":\"2019-03-10T22:19:59+00:00\",\"dateModified\":\"2019-03-10T23:04:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.giantwithin.org\\\/index.php\\\/blog\\\/toyins-blog\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.giantwithin.org\\\/index.php\\\/blog\\\/toyins-blog\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.giantwithin.org\\\/index.php\\\/blog\\\/toyins-blog\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.giantwithin.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Toyin.jpg\",\"contentUrl\":\"https:\\\/\\\/www.giantwithin.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Toyin.jpg\",\"width\":794,\"height\":761,\"caption\":\"Toyin John\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.giantwithin.org\\\/index.php\\\/blog\\\/toyins-blog\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.giantwithin.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.giantwithin.org\\\/index.php\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Toyin&#8217;s Blog\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.giantwithin.org\\\/#website\",\"url\":\"https:\\\/\\\/www.giantwithin.org\\\/\",\"name\":\"Giant Within Ministries\",\"description\":\"Preaching Christ &amp; Transforming Lives\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.giantwithin.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Toyin's Blog - Giant Within Ministries","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.giantwithin.org\/index.php\/blog\/toyins-blog\/","og_locale":"en_US","og_type":"article","og_title":"Toyin's Blog - Giant Within Ministries","og_description":"[vc_row][vc_column][vc_column_text] Welcome to my Blog page.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_basic_grid post_type=&#8221;post&#8221; max_items=&#8221;10&#8243; style=&#8221;load-more&#8221; show_filter=&#8221;yes&#8221; btn_color=&#8221;purple&#8221; btn_add_icon=&#8221;true&#8221; grid_id=&#8221;vc_gid:1552262844284-f1bfb130-4292-9&#8243; taxonomies=&#8221;51&#8243; filter_source=&#8221;category&#8221;][\/vc_column][\/vc_row]","og_url":"https:\/\/www.giantwithin.org\/index.php\/blog\/toyins-blog\/","og_site_name":"Giant Within Ministries","article_modified_time":"2019-03-10T23:04:57+00:00","og_image":[{"url":"https:\/\/www.giantwithin.org\/wp-content\/uploads\/2019\/03\/Toyin-300x288.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.giantwithin.org\/index.php\/blog\/toyins-blog\/","url":"https:\/\/www.giantwithin.org\/index.php\/blog\/toyins-blog\/","name":"Toyin's Blog - Giant Within Ministries","isPartOf":{"@id":"https:\/\/www.giantwithin.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.giantwithin.org\/index.php\/blog\/toyins-blog\/#primaryimage"},"image":{"@id":"https:\/\/www.giantwithin.org\/index.php\/blog\/toyins-blog\/#primaryimage"},"thumbnailUrl":"https:\/\/www.giantwithin.org\/wp-content\/uploads\/2019\/03\/Toyin-300x288.jpg","datePublished":"2019-03-10T22:19:59+00:00","dateModified":"2019-03-10T23:04:57+00:00","breadcrumb":{"@id":"https:\/\/www.giantwithin.org\/index.php\/blog\/toyins-blog\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.giantwithin.org\/index.php\/blog\/toyins-blog\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.giantwithin.org\/index.php\/blog\/toyins-blog\/#primaryimage","url":"https:\/\/www.giantwithin.org\/wp-content\/uploads\/2019\/03\/Toyin.jpg","contentUrl":"https:\/\/www.giantwithin.org\/wp-content\/uploads\/2019\/03\/Toyin.jpg","width":794,"height":761,"caption":"Toyin John"},{"@type":"BreadcrumbList","@id":"https:\/\/www.giantwithin.org\/index.php\/blog\/toyins-blog\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.giantwithin.org\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.giantwithin.org\/index.php\/blog\/"},{"@type":"ListItem","position":3,"name":"Toyin&#8217;s Blog"}]},{"@type":"WebSite","@id":"https:\/\/www.giantwithin.org\/#website","url":"https:\/\/www.giantwithin.org\/","name":"Giant Within Ministries","description":"Preaching Christ &amp; Transforming Lives","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.giantwithin.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.giantwithin.org\/index.php\/wp-json\/wp\/v2\/pages\/7693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.giantwithin.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.giantwithin.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.giantwithin.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.giantwithin.org\/index.php\/wp-json\/wp\/v2\/comments?post=7693"}],"version-history":[{"count":11,"href":"https:\/\/www.giantwithin.org\/index.php\/wp-json\/wp\/v2\/pages\/7693\/revisions"}],"predecessor-version":[{"id":7695,"href":"https:\/\/www.giantwithin.org\/index.php\/wp-json\/wp\/v2\/pages\/7693\/revisions\/7695"}],"up":[{"embeddable":true,"href":"https:\/\/www.giantwithin.org\/index.php\/wp-json\/wp\/v2\/pages\/6600"}],"wp:attachment":[{"href":"https:\/\/www.giantwithin.org\/index.php\/wp-json\/wp\/v2\/media?parent=7693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}